{"id":9941,"date":"2021-07-15T19:50:10","date_gmt":"2021-07-15T17:50:10","guid":{"rendered":"https:\/\/www.highnoon.art\/?page_id=9941"},"modified":"2022-11-28T19:37:41","modified_gmt":"2022-11-28T17:37:41","slug":"you-are-here-wolken-kuckucks-heim","status":"publish","type":"page","link":"https:\/\/www.highnoon.art\/es\/you-are-here-wolken-kuckucks-heim\/","title":{"rendered":"YOU ARE HERE:@\/\/\/wolken.kuckucks.heim"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"9941\" class=\"elementor elementor-9941\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-22bc08d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"22bc08d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f5d6cce\" data-id=\"f5d6cce\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-71e40c8 elementor-widget elementor-widget-image\" data-id=\"71e40c8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/www.highnoon.art\/wp-content\/uploads\/2021\/07\/Cloud-Optimiert-1024x1024.png\" class=\"attachment-large size-large wp-image-10130\" alt=\"\" srcset=\"https:\/\/www.highnoon.art\/wp-content\/uploads\/2021\/07\/Cloud-Optimiert-1024x1024.png 1024w, https:\/\/www.highnoon.art\/wp-content\/uploads\/2021\/07\/Cloud-Optimiert-300x300.png 300w, https:\/\/www.highnoon.art\/wp-content\/uploads\/2021\/07\/Cloud-Optimiert-150x150.png 150w, https:\/\/www.highnoon.art\/wp-content\/uploads\/2021\/07\/Cloud-Optimiert-768x768.png 768w, https:\/\/www.highnoon.art\/wp-content\/uploads\/2021\/07\/Cloud-Optimiert-12x12.png 12w, https:\/\/www.highnoon.art\/wp-content\/uploads\/2021\/07\/Cloud-Optimiert.png 1080w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f8b2699 elementor-widget elementor-widget-text-editor\" data-id=\"f8b2699\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"page\" title=\"Page 2\"><div class=\"layoutArea\"><div class=\"column\"><p><strong>YOU ARE HERE:@\/\/\/wolken.kuckucks.heim<\/strong><br \/><strong>Ein interaktives, immersives und pandemiekompatibles* Ausstellungskonzept<\/strong><\/p><p>YOU ARE HERE:@\/\/\/wolken.kuckucks.heim ist ein interaktives und immersives Ausstellungskonzept fu\u0308r Fotografie mit eigens dafu\u0308r komponierten Soundscapes, dass das Kunsterlebnis des Besuchers in den Mittelpunkt stellt. Es ist in der Bandbreite seiner vielfa\u0308ltigen Facetten [r]evolutiona\u0308r und neuartig. Eine Ausstellung ist in Gro\u0308\u00dfe und Geometrie skalierbar und kann aus derzeit zwei fertig realisierten Themen- und Bilderwelten gestaltet werden.<\/p><p>Das Ausstellungsdesign ist kompatibel* mit den durch die Pandemie erforderlichen Schutzma\u00df- nahmen.<\/p><p>Ausgangspunkt einer Ausstellung sind Fotografien und\/oder Videografien in Gro\u0308\u00dfen bis zu 4&#215;6 Metern, die jedoch anders als in Fotoausstellungen fu\u0308r gewo\u0308hnlich u\u0308blich, nicht Bild neben Bild im Ausstellungsraum ha\u0308ngen. Fu\u0308r die ausgewa\u0308hlten Arbeiten wird in Kooperation mit Ausstellungsarchitekten und -designern gerade ein Parcours entwickelt, der jede Arbeit so inszeniert und so exponiert pra\u0308sentiert, dass der Betrachter ohne visuelle Ablenkung in das jeweilige Werk eintauchen kann. Hierzu ko\u0308nnen wir, gemeinsam mit Kurator*innen, aus derzeit u\u0308ber 250 realisierten Fotografien\/ Videografien aus 2 Werkgruppen eine Auswahl vornehmen und eine Dramaturgie entwickeln, die die Kraft hat, den Betrachter, u\u0308ber die Auseinandersetzung mit den in den Arbeiten gezeigten Inhalten hinaus, mit sich selbst und seiner Umwelt in Kontakt kommen zu lassen.<\/p><p><strong># 1. High Noon<br \/><\/strong>Fotografien aus Berlin, Hamburg, Frankfurt, Mu\u0308nchen, Florenz, London, Madrid, Mailand, Rom, Siena, Venedig und weiteren Orten unter Einfluss des Corona Shutdown, aufgenommen seit Ma\u0308rz 2020<\/p><p><strong><a href=\"https:\/\/www.berge-wiesen-waelder.art\" target=\"_blank\" rel=\"noopener\" data-wplink-edit=\"true\"><span style=\"color: #339933;\"># 2. Berge, Wiesen und Wa\u0308lder<\/span><\/a><\/strong><br \/>seit Januar 2019 in Deutschland, England, Frankreich, O\u0308sterreich und der Schweiz realisierte gro\u00dfformatige Landschaftsaufnahmen<\/p><p>Ausschlaggebend fu\u0308r das immersive Erlebnis und den Impact auf den Betrachter ist dabei, dass wir nicht nur in der Lage sind Kla\u0308nge, in 3d Audio, interaktiv dem jeweiligen Standort des Betrachters im Ausstellungsraum und seiner Blickrichtung entsprechend, in Echtzeit auf seinen Kopfho\u0308rer zu streamen \u2013 mehr noch \u2013 wir ko\u0308nnen die Klangwelten daru\u0308ber hinaus auch, fu\u0308r jeden Betrachter individuell, ko\u0308rperlich spu\u0308rbar machen.<\/p><p>So erha\u0308lt der Ausstellungsbesucher neben dem visuellen und akustischen Erlebnis zusa\u0308tzlich, ein generell angenehmes, mal beru\u0308hrendes, mal irritierendes taktiles Erlebnis hinzu. Das fu\u0308hrt dazu, dass er das Erlebte nicht nur als u\u0308berraschend und neuartig empfindet, sondern es etwas bei ihm auslo\u0308st, das in vielen Fa\u0308llen den Focus nochmals fu\u0308r das Gesehene scha\u0308rft oder es gar in Bewegung bringt.<\/p><p>Der Grad der Interaktion fu\u0308r den Besucher ist ebenso, wie die Anzahl der gezeigten Werkgruppen skalierbar &#8211; <strong># 1 und # 2<\/strong> &#8211; beide ko\u0308nnen fu\u0308r sich alleine stehen \u2013 beide ko\u0308nnen aber auch durch ein Verbindungsmodul, das wir den <strong>\u201eRaum des Unbehagens\u201c<\/strong> nennen, miteinander verknu\u0308pft werden und gehen so eine spannende Symbiose ein.<\/p><p>Im <strong>\u201eRaum des Unbehagens\u201c<\/strong> sind 7 Arbeiten mit gesellschaftliche Themen, mit denen wir wa\u0308hrend des Herstellungsprozesses zu YOU ARE HERE:@\/\/\/wolken.kuckucks.heim, sei es als Bu\u0308rger oder als Ku\u0308nstler, z.B. in der Auseinandersetzung mit einem Motiv, konfrontiert wurden.<\/p><div class=\"page\" title=\"Page 3\"><div class=\"layoutArea\"><div class=\"column\"><p>Die erreichbare Interaktivita\u0308t des Betrachters, kann in seiner Basisauslegung so beschrieben werden: Ortung des Besuchers im Ausstellungsraum auf 10 cm genau, bei gleichzeitiger Erfassung seiner Blickrichtung auf 1 Grad pra\u0308zise und dementsprechender individueller Ausgabe der Medien auf den Kopfho\u0308rer.<\/p><p>Der Besucher nimmt von der ganzen technischen Komplexita\u0308t und der eingesetzten Hightech nichts bewusst war \u2013 denn er bewegt sich nach kurzer Zeit bereits ganz selbstversta\u0308ndlich fast meditativ auf einem, von ihm fast schon als organisch wahrgenommenen Pfad und vergisst dabei nicht nur Zeit und Raum, sondern kann, sofern er sich einla\u0308sst , vielleicht sogar Momente erleben in denen er sich im Spiegelbild eines Werkes selbst erfa\u0308hrt.<\/p><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-11eb2b0 elementor-widget elementor-widget-text-editor\" data-id=\"11eb2b0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>*Anmerkungen zu der Pandemiekompatibilita\u0308t unseres Ausstellungskonzeptes<\/strong><\/p><p>Die von uns eingesetzte Technik stammt aus Europa, ist verfu\u0308gbar und einsatzbereit und wird individuell fu\u0308r die jeweiligen Ausstellungsra\u0308ume und das Ausstellungsdesign konfiguriert. Fu\u0308r die Interaktivita\u0308t in unserem Ausstellungskonzept ist die pra\u0308zise Erfassung des Standortes jedes Besuchers unerla\u0308sslich.<\/p><p>In Zeiten einer Pandemie und den daraus resultierenden unerla\u0308sslichen und vielfa\u0308ltigen Sicherheitsvorkehrungen zum Schutz der Ausstellungsbesucher sowie der Mitarbeiter, kommt einem Aspekt eine herausragende Bedeutung zu: <span style=\"text-decoration: underline;\">Dem Abstand einzelner zueinander.<\/span><\/p><p>Bei der Einhaltung der Abstandsregeln, egal ob der Abstandskoeffizient mit 1,5, 2 oder 2,5 Meter definiert wird, spielt unser System, neben den kunstspezifischen Fa\u0308higkeiten, seine Einzigartigkeit auch im Hinblick auf Sicherheitsaspekte aus. Denn wir sind nicht nur in der Lage den Abstand Einzelner zueinander auf 10 Zentimeter genau zu u\u0308berwachen, wir ko\u0308nnen auch Gruppen bilden und deren Abstand zu anderen u\u0308berwachen um bei zu geringem Abstand Warnungen auf die jeweiligen Kopfho\u0308rer ausgeben<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>YOU ARE HERE:@\/\/\/wolken.kuckucks.heimEin interaktives, immersives und pandemiekompatibles* Ausstellungskonzept YOU ARE HERE:@\/\/\/wolken.kuckucks.heim ist ein interaktives und immersives Ausstellungskonzept fu\u0308r Fotografie mit eigens dafu\u0308r komponierten Soundscapes, dass das Kunsterlebnis des Besuchers in den Mittelpunkt stellt. Es ist in der Bandbreite seiner vielfa\u0308ltigen Facetten [r]evolutiona\u0308r und neuartig. Eine Ausstellung ist in Gro\u0308\u00dfe und Geometrie skalierbar und kann aus [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-9941","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>YOU ARE HERE:@\/\/\/wolken.kuckucks.heim\u2028 - High Noon<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.highnoon.art\/es\/you-are-here-wolken-kuckucks-heim\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"YOU ARE HERE:@\/\/\/wolken.kuckucks.heim\u2028 - High Noon\" \/>\n<meta property=\"og:description\" content=\"YOU ARE HERE:@\/\/\/wolken.kuckucks.heimEin interaktives, immersives und pandemiekompatibles* Ausstellungskonzept YOU ARE HERE:@\/\/\/wolken.kuckucks.heim ist ein interaktives und immersives Ausstellungskonzept fu\u0308r Fotografie mit eigens dafu\u0308r komponierten Soundscapes, dass das Kunsterlebnis des Besuchers in den Mittelpunkt stellt. Es ist in der Bandbreite seiner vielfa\u0308ltigen Facetten [r]evolutiona\u0308r und neuartig. Eine Ausstellung ist in Gro\u0308\u00dfe und Geometrie skalierbar und kann aus [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.highnoon.art\/es\/you-are-here-wolken-kuckucks-heim\/\" \/>\n<meta property=\"og:site_name\" content=\"High Noon\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-28T17:37:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.highnoon.art\/wp-content\/uploads\/2021\/07\/Cloud-Optimiert-1024x1024.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.highnoon.art\\\/you-are-here-wolken-kuckucks-heim\\\/\",\"url\":\"https:\\\/\\\/www.highnoon.art\\\/you-are-here-wolken-kuckucks-heim\\\/\",\"name\":\"YOU ARE HERE:@\\\/\\\/\\\/wolken.kuckucks.heim\\u2028 - High Noon\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.highnoon.art\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.highnoon.art\\\/you-are-here-wolken-kuckucks-heim\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.highnoon.art\\\/you-are-here-wolken-kuckucks-heim\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.highnoon.art\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/Cloud-Optimiert-1024x1024.png\",\"datePublished\":\"2021-07-15T17:50:10+00:00\",\"dateModified\":\"2022-11-28T17:37:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.highnoon.art\\\/you-are-here-wolken-kuckucks-heim\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.highnoon.art\\\/you-are-here-wolken-kuckucks-heim\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.highnoon.art\\\/you-are-here-wolken-kuckucks-heim\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.highnoon.art\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/Cloud-Optimiert-1024x1024.png\",\"contentUrl\":\"https:\\\/\\\/www.highnoon.art\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/Cloud-Optimiert-1024x1024.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.highnoon.art\\\/you-are-here-wolken-kuckucks-heim\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.highnoon.art\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"YOU ARE HERE:@\\\/\\\/\\\/wolken.kuckucks.heim\\u2028\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.highnoon.art\\\/#website\",\"url\":\"https:\\\/\\\/www.highnoon.art\\\/\",\"name\":\"High Noon\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.highnoon.art\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.highnoon.art\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.highnoon.art\\\/#organization\",\"name\":\"High Noon\",\"url\":\"https:\\\/\\\/www.highnoon.art\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.highnoon.art\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.highnoon.art\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/high-noon_white_moved.jpg\",\"contentUrl\":\"https:\\\/\\\/www.highnoon.art\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/high-noon_white_moved.jpg\",\"width\":1137,\"height\":159,\"caption\":\"High Noon\"},\"image\":{\"@id\":\"https:\\\/\\\/www.highnoon.art\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"YOU ARE HERE:@\/\/\/wolken.kuckucks.heim - High Noon","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.highnoon.art\/es\/you-are-here-wolken-kuckucks-heim\/","og_locale":"es_ES","og_type":"article","og_title":"YOU ARE HERE:@\/\/\/wolken.kuckucks.heim\u2028 - High Noon","og_description":"YOU ARE HERE:@\/\/\/wolken.kuckucks.heimEin interaktives, immersives und pandemiekompatibles* Ausstellungskonzept YOU ARE HERE:@\/\/\/wolken.kuckucks.heim ist ein interaktives und immersives Ausstellungskonzept fu\u0308r Fotografie mit eigens dafu\u0308r komponierten Soundscapes, dass das Kunsterlebnis des Besuchers in den Mittelpunkt stellt. Es ist in der Bandbreite seiner vielfa\u0308ltigen Facetten [r]evolutiona\u0308r und neuartig. Eine Ausstellung ist in Gro\u0308\u00dfe und Geometrie skalierbar und kann aus [&hellip;]","og_url":"https:\/\/www.highnoon.art\/es\/you-are-here-wolken-kuckucks-heim\/","og_site_name":"High Noon","article_modified_time":"2022-11-28T17:37:41+00:00","og_image":[{"url":"https:\/\/www.highnoon.art\/wp-content\/uploads\/2021\/07\/Cloud-Optimiert-1024x1024.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.highnoon.art\/you-are-here-wolken-kuckucks-heim\/","url":"https:\/\/www.highnoon.art\/you-are-here-wolken-kuckucks-heim\/","name":"YOU ARE HERE:@\/\/\/wolken.kuckucks.heim - High Noon","isPartOf":{"@id":"https:\/\/www.highnoon.art\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.highnoon.art\/you-are-here-wolken-kuckucks-heim\/#primaryimage"},"image":{"@id":"https:\/\/www.highnoon.art\/you-are-here-wolken-kuckucks-heim\/#primaryimage"},"thumbnailUrl":"https:\/\/www.highnoon.art\/wp-content\/uploads\/2021\/07\/Cloud-Optimiert-1024x1024.png","datePublished":"2021-07-15T17:50:10+00:00","dateModified":"2022-11-28T17:37:41+00:00","breadcrumb":{"@id":"https:\/\/www.highnoon.art\/you-are-here-wolken-kuckucks-heim\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.highnoon.art\/you-are-here-wolken-kuckucks-heim\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.highnoon.art\/you-are-here-wolken-kuckucks-heim\/#primaryimage","url":"https:\/\/www.highnoon.art\/wp-content\/uploads\/2021\/07\/Cloud-Optimiert-1024x1024.png","contentUrl":"https:\/\/www.highnoon.art\/wp-content\/uploads\/2021\/07\/Cloud-Optimiert-1024x1024.png"},{"@type":"BreadcrumbList","@id":"https:\/\/www.highnoon.art\/you-are-here-wolken-kuckucks-heim\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.highnoon.art\/"},{"@type":"ListItem","position":2,"name":"YOU ARE HERE:@\/\/\/wolken.kuckucks.heim\u2028"}]},{"@type":"WebSite","@id":"https:\/\/www.highnoon.art\/#website","url":"https:\/\/www.highnoon.art\/","name":"High Noon","description":"","publisher":{"@id":"https:\/\/www.highnoon.art\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.highnoon.art\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.highnoon.art\/#organization","name":"High Noon","url":"https:\/\/www.highnoon.art\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.highnoon.art\/#\/schema\/logo\/image\/","url":"https:\/\/www.highnoon.art\/wp-content\/uploads\/2021\/07\/high-noon_white_moved.jpg","contentUrl":"https:\/\/www.highnoon.art\/wp-content\/uploads\/2021\/07\/high-noon_white_moved.jpg","width":1137,"height":159,"caption":"High Noon"},"image":{"@id":"https:\/\/www.highnoon.art\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.highnoon.art\/es\/wp-json\/wp\/v2\/pages\/9941","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.highnoon.art\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.highnoon.art\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.highnoon.art\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.highnoon.art\/es\/wp-json\/wp\/v2\/comments?post=9941"}],"version-history":[{"count":0,"href":"https:\/\/www.highnoon.art\/es\/wp-json\/wp\/v2\/pages\/9941\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.highnoon.art\/es\/wp-json\/wp\/v2\/media?parent=9941"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}